{"id":12905,"date":"2026-05-13T09:19:43","date_gmt":"2026-05-13T12:19:43","guid":{"rendered":"https:\/\/consrosario.esteri.it\/news\/dal_consolato\/2026\/05\/maestri-del-teatro-italiano\/"},"modified":"2026-05-13T09:26:22","modified_gmt":"2026-05-13T12:26:22","slug":"maestri-del-teatro-italiano","status":"publish","type":"post","link":"https:\/\/consrosario.esteri.it\/es\/news\/dal_consolato\/2026\/05\/maestri-del-teatro-italiano\/","title":{"rendered":"Maestros del teatro italiano"},"content":{"rendered":"<p style=\"text-align: justify;\" data-start=\"34\" data-end=\"485\">El mini ciclo propone un recorrido a trav\u00e9s de dos figuras fundamentales del teatro italiano: <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Carlo Goldoni<\/span><\/span> y <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Luigi Pirandello<\/span><\/span>. A trav\u00e9s de una introducci\u00f3n a sus contextos hist\u00f3ricos y est\u00e9ticos, se abordar\u00e1n dos momentos clave de la evoluci\u00f3n de la escena italiana: la reforma teatral promovida por Goldoni en el siglo XVIII y la renovaci\u00f3n del lenguaje dram\u00e1tico propuesta por Pirandello en el siglo XX.<\/p>\n<p style=\"text-align: justify;\" data-start=\"487\" data-end=\"712\" data-is-last-node=\"\" data-is-only-node=\"\">Asimismo, se presentar\u00e1n dos obras emblem\u00e1ticas de la dramaturgia italiana, <em><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">La locandiera<\/span><\/span><\/em> y <em><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Sei personaggi in cerca d&#8217;autore<\/span><\/span><\/em>, consideradas hitos fundamentales de la historia del teatro occidental.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12892 img-fluid aligncenter\" src=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-820x1024.png\" alt=\"\" width=\"640\" height=\"799\" srcset=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-820x1024.png 820w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-240x300.png 240w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-768x960.png 768w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x.png 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12898 img-fluid aligncenter\" src=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-820x1024.png\" alt=\"\" width=\"640\" height=\"799\" srcset=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-820x1024.png 820w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-240x300.png 240w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-768x960.png 768w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x.png 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"El mini ciclo propone un recorrido a trav\u00e9s de dos figuras fundamentales del teatro italiano: Carlo Goldoni y Luigi Pirandello. A trav\u00e9s de una introducci\u00f3n a sus contextos hist\u00f3ricos y est\u00e9ticos, se abordar\u00e1n dos momentos clave de la evoluci\u00f3n de la escena italiana: la reforma teatral promovida por Goldoni en el siglo XVIII y la [&hellip;]","protected":false},"author":5,"featured_media":12890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-12905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/posts\/12905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=12905"}],"version-history":[{"count":2,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/posts\/12905\/revisions"}],"predecessor-version":[{"id":12908,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/posts\/12905\/revisions\/12908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/media\/12890"}],"wp:attachment":[{"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=12905"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consrosario.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=12905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}