{"id":12886,"date":"2026-05-13T09:19:43","date_gmt":"2026-05-13T12:19:43","guid":{"rendered":"https:\/\/consrosario.esteri.it\/?p=12886"},"modified":"2026-05-13T09:21:52","modified_gmt":"2026-05-13T12:21:52","slug":"maestri-del-teatro-italiano","status":"publish","type":"post","link":"https:\/\/consrosario.esteri.it\/it\/news\/dal_consolato\/2026\/05\/maestri-del-teatro-italiano\/","title":{"rendered":"Maestri del teatro Italiano"},"content":{"rendered":"<p style=\"text-align: justify;\">Il mini ciclo propone un percorso attraverso due figure fondamentali del teatro italiano: Carlo Goldoni e Luigi Pirandello. Attraverso un\u2019introduzione ai loro contesti storici ed estetici, saranno affrontati due momenti chiave dell\u2019evoluzione della scena italiana: la riforma teatrale promossa da Goldoni nel Settecento e il rinnovamento del linguaggio drammatico proposto da Pirandello nel Novecento.<\/p>\n<p style=\"text-align: justify;\">Saranno inoltre presentate due opere emblematiche della drammaturgia italiana, <em>La locandiera<\/em> e <em>Sei personaggi in cerca d&#8217;autore<\/em>, considerate pietre miliari della storia del teatro occidentale.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12892 img-fluid aligncenter\" src=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-820x1024.png\" alt=\"\" width=\"640\" height=\"799\" srcset=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-820x1024.png 820w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-240x300.png 240w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x-768x960.png 768w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_18@2x.png 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12898 img-fluid aligncenter\" src=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-820x1024.png\" alt=\"\" width=\"640\" height=\"799\" srcset=\"https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-820x1024.png 820w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-240x300.png 240w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x-768x960.png 768w, https:\/\/consrosario.esteri.it\/wp-content\/uploads\/2026\/05\/CICLOmaestri_28@2x.png 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"Il mini ciclo propone un percorso attraverso due figure fondamentali del teatro italiano: Carlo Goldoni e Luigi Pirandello. Attraverso un\u2019introduzione ai loro contesti storici ed estetici, saranno affrontati due momenti chiave dell\u2019evoluzione della scena italiana: la riforma teatrale promossa da Goldoni nel Settecento e il rinnovamento del linguaggio drammatico proposto da Pirandello nel Novecento. Saranno [&hellip;]","protected":false},"author":5,"featured_media":12887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-12886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/posts\/12886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=12886"}],"version-history":[{"count":2,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/posts\/12886\/revisions"}],"predecessor-version":[{"id":12907,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/posts\/12886\/revisions\/12907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/media\/12887"}],"wp:attachment":[{"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=12886"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consrosario.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=12886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}